{"id":3799,"date":"2025-02-06T15:06:01","date_gmt":"2025-02-06T20:06:01","guid":{"rendered":"https:\/\/3.96.194.27\/?post_type=docs&#038;p=3799"},"modified":"2025-02-06T15:06:02","modified_gmt":"2025-02-06T20:06:02","password":"","slug":"automatiser-des-actions","status":"publish","type":"docs","link":"https:\/\/modellium.com\/en\/docs\/automatiser-des-actions\/","title":{"rendered":"Automatiser des actions"},"content":{"rendered":"<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Automatiser-des-actions-Video.mp4\"><\/video><\/figure>\n\n\n\n<p>Cet article d\u00e9crit comment automatiser des actions pour les requ\u00eates.<\/p>\n\n\n\n<p><em>Si vous n\u2019avez pas de compte V+, <\/em><a href=\"https:\/\/modellium.com\/en\/demandez-une-demo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>cliquez-ici<\/em><\/a><em> pour une d\u00e9monstration.<\/em>&nbsp;<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-1-acceder-aux-parametres\"><figure class=\"wp-block-image aligncenter size-large is-resized\">\u00c9tape 1 : <strong style=\"color: revert; font-size: revert;\">Acc\u00e9der aux param\u00e8tres<\/strong><\/figure><\/h2>\n\n\n\n<p>Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur <strong>\u00ab Requ\u00eate \u00bb<\/strong>, puis sur <strong>\u00ab Param\u00e8tres \u00bb<\/strong>. Par d\u00e9faut, cette interface affiche la liste des param\u00e8tres li\u00e9s aux requ\u00eates.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-1024x509.png\" alt=\"\" class=\"wp-image-20120\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Pour acc\u00e9der \u00e0 la cr\u00e9ation d\u2019automatisations d\u2019actions, cliquez sur <strong>\u00ab Actions \u00bb<\/strong>, puis sur <strong>\u00ab Liste des actions \u00bb<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-1024x509.png\" alt=\"\" class=\"wp-image-20121\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Choix-de-parametres-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-2-consulter-la-liste-des-actions\">\u00c9tape 2 : <strong>Consulter la liste des actions<\/strong><\/h2>\n\n\n\n<p>S\u00e9lectionnez le type d&rsquo;affectation \u00ab Requ\u00eate \u00bb.<\/p>\n\n\n\n<p>\ud83d\udccc La grille affiche par d\u00e9faut plusieurs informations :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Titre de l\u2019action<\/li>\n\n\n\n<li>Dates de cr\u00e9ation et de modification<\/li>\n\n\n\n<li>Options disponibles dans la colonne \u00ab Actions \u00bb :<br>\ud83d\udd39 \u00c9diter l\u2019action<br>\ud83d\udd39 Supprimer l\u2019action<\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udca1 <strong>Astuce<\/strong> : Vous pouvez trier et filtrer chaque colonne selon vos besoins.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-1024x509.png\" alt=\"\" class=\"wp-image-20122\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Consulter-la-liste-des-actions-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-3-creez-une-nouvelle-action\">\u00c9tape 3 : <strong>Cr\u00e9ez une nouvelle action<\/strong><\/h2>\n\n\n\n<p>1\ufe0f\u20e3 Cliquez sur le bouton bleu<strong> \u00ab Nouvelle Action \u00bb<\/strong> (en haut \u00e0 droite de l\u2019\u00e9cran).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-1024x509.png\" alt=\"\" class=\"wp-image-20123\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creez-une-nouvelle-action-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>2\ufe0f\u20e3 L\u2019interface d\u2019\u00e9dition de l\u2019action s\u2019ouvre.<br>3\ufe0f\u20e3 <strong>Remplissez les champs suivants<\/strong> :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nom de l&rsquo;action (<em>obligatoire<\/em>).<\/li>\n\n\n\n<li>Description (<em>facultatif, max. 250 caract\u00e8res<\/em>).<br>4\ufe0f\u20e3 Configurez les modificateurs : d\u00e9finissez les champs \u00e0 modifier lors de l\u2019ex\u00e9cution de l\u2019action (ex. : Statut, D\u00e9partement, Contributeur).<br>5\ufe0f\u20e3 <strong>Cliquez sur \u00ab Enregistrer \u00bb<\/strong> (bouton bleu en haut de l\u2019interface).<\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udccc Une fois enregistr\u00e9e, l\u2019action appara\u00eetra dans la liste des actions de la cat\u00e9gorie d\u2019affectation requ\u00eate.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--1024x509.png\" alt=\"\" class=\"wp-image-20152\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/section-Modificateurs--360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Lors de la consultation d\u2019une requ\u00eate, un bouton <strong>\u00ab Actions \u00bb<\/strong> (en haut \u00e0 droite) affichera d\u00e9sormais l\u2019action que vous avez cr\u00e9\u00e9e. Vous pourrez ainsi effectuer plusieurs modifications en <strong>un seul clic<\/strong>.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-4-modifiez-une-action\">\u00c9tape 4 : <strong>Modifiez une action<\/strong><\/h2>\n\n\n\n<p>1\ufe0f\u20e3 <strong>Cliquez sur l\u2019ic\u00f4ne \u00ab \u00c9diter \u00bb<\/strong> dans la liste des actions.<br>2\ufe0f\u20e3 L\u2019interface d\u2019\u00e9dition de l\u2019action s\u2019ouvre.<br>3\ufe0f\u20e3 Apportez vos modifications.<br>4\ufe0f\u20e3 <strong>Cliquez sur \u00ab Enregistrer \u00bb<\/strong> pour valider vos changements.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-1024x509.png\" alt=\"\" class=\"wp-image-20129\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-liste-des-actions-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-5-supprimez-une-action\">\u00c9tape 5 : <strong>Supprimez une action<\/strong><\/h2>\n\n\n\n<p>1\ufe0f\u20e3 <strong>Cliquez sur l\u2019ic\u00f4ne \u00ab Supprimer \u00bb<\/strong> dans la liste des actions.<br>2\ufe0f\u20e3 Une fen\u00eatre de confirmation s\u2019affiche.<br>3\ufe0f\u20e3 <strong>Cliquez sur \u00ab Supprimer \u00bb<\/strong>.<\/p>\n\n\n\n<p>\ud83d\udea8 <strong>Attention<\/strong> : Une fois supprim\u00e9e, l\u2019action ne figurera plus dans la liste des actions.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-1024x509.png\" alt=\"\" class=\"wp-image-20130\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimez-une-action-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Cet article d\u00e9crit comment automatiser des actions pour les requ\u00eates. Si vous n\u2019avez pas de compte V+, cliquez-ici pour une d\u00e9monstration.&nbsp; \u00c9tape 1 : Acc\u00e9der aux param\u00e8tres Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur \u00ab Requ\u00eate \u00bb, puis sur \u00ab Param\u00e8tres \u00bb. Par d\u00e9faut, cette interface affiche la liste des param\u00e8tres li\u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","footnotes":""},"doc_category":[60],"doc_tag":[],"knowledge_base":[55],"class_list":["post-3799","docs","type-docs","status-publish","hentry","doc_category-approfondir-requete","knowledge_base-requetes-citoyennes"],"acf":[],"year_month":"2026-05","word_count":338,"total_views":"2478","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"David Teixeira","author_nicename":"davidteix","author_url":"https:\/\/modellium.com\/en\/author\/davidteix\/"},"doc_category_info":[{"term_name":"Approfondir","term_url":"https:\/\/modellium.com\/en\/banque-de-connaissances\/requetes-citoyennes\/approfondir-requete\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Automatiser des actions - Modellium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/modellium.com\/en\/docs\/automatiser-des-actions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatiser des actions - Modellium\" \/>\n<meta property=\"og:description\" content=\"Cet article d\u00e9crit comment automatiser des actions pour les requ\u00eates. Si vous n\u2019avez pas de compte V+, cliquez-ici pour une d\u00e9monstration.&nbsp; \u00c9tape 1 : Acc\u00e9der aux param\u00e8tres Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur \u00ab Requ\u00eate \u00bb, puis sur \u00ab Param\u00e8tres \u00bb. Par d\u00e9faut, cette interface affiche la liste des param\u00e8tres li\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/modellium.com\/en\/docs\/automatiser-des-actions\/\" \/>\n<meta property=\"og:site_name\" content=\"Modellium\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Modellium\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T20:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3833\" \/>\n\t<meta property=\"og:image:height\" content=\"1906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/\",\"url\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/\",\"name\":\"Automatiser des actions - Modellium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Acceder-aux-parametres-1-1024x509.png\",\"datePublished\":\"2025-02-06T20:06:01+00:00\",\"dateModified\":\"2025-02-06T20:06:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Acceder-aux-parametres-1-1024x509.png\",\"contentUrl\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Acceder-aux-parametres-1-1024x509.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/automatiser-des-actions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explorez les produits\",\"item\":\"https:\\\/\\\/modellium.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Requ\u00eates citoyennes\",\"item\":\"https:\\\/\\\/modellium.com\\\/banque-de-connaissances\\\/requetes-citoyennes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Automatiser des actions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/modellium.com\\\/#website\",\"url\":\"https:\\\/\\\/modellium.com\\\/\",\"name\":\"Modellium\",\"description\":\"Solutions num\u00e9riques innovantes pour le domaine municipal\",\"publisher\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/modellium.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/modellium.com\\\/#organization\",\"name\":\"Modellium\",\"url\":\"https:\\\/\\\/modellium.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/modellium.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-modellium-desktop.svg\",\"contentUrl\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-modellium-desktop.svg\",\"width\":149,\"height\":30,\"caption\":\"Modellium\"},\"image\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Modellium\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/modellium\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Automatiser des actions - Modellium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/modellium.com\/en\/docs\/automatiser-des-actions\/","og_locale":"en_US","og_type":"article","og_title":"Automatiser des actions - Modellium","og_description":"Cet article d\u00e9crit comment automatiser des actions pour les requ\u00eates. Si vous n\u2019avez pas de compte V+, cliquez-ici pour une d\u00e9monstration.&nbsp; \u00c9tape 1 : Acc\u00e9der aux param\u00e8tres Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur \u00ab Requ\u00eate \u00bb, puis sur \u00ab Param\u00e8tres \u00bb. Par d\u00e9faut, cette interface affiche la liste des param\u00e8tres li\u00e9s [&hellip;]","og_url":"https:\/\/modellium.com\/en\/docs\/automatiser-des-actions\/","og_site_name":"Modellium","article_publisher":"https:\/\/www.facebook.com\/Modellium\/","article_modified_time":"2025-02-06T20:06:02+00:00","og_image":[{"width":3833,"height":1906,"url":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/","url":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/","name":"Automatiser des actions - Modellium","isPartOf":{"@id":"https:\/\/modellium.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/#primaryimage"},"image":{"@id":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/#primaryimage"},"thumbnailUrl":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-1024x509.png","datePublished":"2025-02-06T20:06:01+00:00","dateModified":"2025-02-06T20:06:02+00:00","breadcrumb":{"@id":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/modellium.com\/docs\/automatiser-des-actions\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/#primaryimage","url":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-1024x509.png","contentUrl":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Acceder-aux-parametres-1-1024x509.png"},{"@type":"BreadcrumbList","@id":"https:\/\/modellium.com\/docs\/automatiser-des-actions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explorez les produits","item":"https:\/\/modellium.com\/"},{"@type":"ListItem","position":2,"name":"Requ\u00eates citoyennes","item":"https:\/\/modellium.com\/banque-de-connaissances\/requetes-citoyennes\/"},{"@type":"ListItem","position":3,"name":"Automatiser des actions"}]},{"@type":"WebSite","@id":"https:\/\/modellium.com\/#website","url":"https:\/\/modellium.com\/","name":"Modellium","description":"Solutions num\u00e9riques innovantes pour le domaine municipal","publisher":{"@id":"https:\/\/modellium.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/modellium.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/modellium.com\/#organization","name":"Modellium","url":"https:\/\/modellium.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/modellium.com\/#\/schema\/logo\/image\/","url":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/06\/logo-modellium-desktop.svg","contentUrl":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/06\/logo-modellium-desktop.svg","width":149,"height":30,"caption":"Modellium"},"image":{"@id":"https:\/\/modellium.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Modellium\/","https:\/\/www.linkedin.com\/company\/modellium\/"]}]}},"jetpack_sharing_enabled":true,"knowledge_base_info":[{"term_name":"Requ\u00eates citoyennes","term_url":"https:\/\/modellium.com\/en\/banque-de-connaissances\/requetes-citoyennes\/","term_slug":"requetes-citoyennes"}],"knowledge_base_slug":["requetes-citoyennes"],"_links":{"self":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs\/3799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/comments?post=3799"}],"version-history":[{"count":36,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs\/3799\/revisions"}],"predecessor-version":[{"id":20683,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs\/3799\/revisions\/20683"}],"wp:attachment":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/media?parent=3799"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/doc_category?post=3799"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/doc_tag?post=3799"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/knowledge_base?post=3799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}