{"id":3793,"date":"2025-02-06T15:03:59","date_gmt":"2025-02-06T20:03:59","guid":{"rendered":"https:\/\/3.96.194.27\/?post_type=docs&#038;p=3793"},"modified":"2025-02-06T15:38:10","modified_gmt":"2025-02-06T20:38:10","password":"","slug":"creer-une-une-vue-personnalisee","status":"publish","type":"docs","link":"https:\/\/modellium.com\/en\/docs\/creer-une-une-vue-personnalisee\/","title":{"rendered":"Cr\u00e9er une une vue personnalis\u00e9e"},"content":{"rendered":"<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Creer-une-une-vue-personnalisee-Video.mp4\"><\/video><\/figure>\n\n\n\n<p>Cet article d\u00e9crit comment cr\u00e9er une vue personnalis\u00e9e pour g\u00e9rer vos requ\u00eates.<\/p>\n\n\n\n<p><em>Si vous n\u2019avez pas votre compte V+, <\/em><a href=\"https:\/\/modellium.com\/en\/demandez-une-demo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>cliquez ici<\/em><\/a><em> pour une d\u00e9monstration.<\/em><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-1-acceder-au-module-requete\">\u00c9tape 1 : <strong>Acc\u00e9der au module Requ\u00eate<\/strong><\/h2>\n\n\n\n<p>Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur <strong>\u00ab Requ\u00eate \u00bb<\/strong>.<\/p>\n\n\n\n<p>\ud83d\udccc <strong>Par d\u00e9faut, vous acc\u00e9dez \u00e0 l&rsquo;onglet \u00ab Mes affectations \u00bb<\/strong>, qui affiche :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les <strong>affectations en statut ouvert<\/strong> dont vous \u00eates contributeur.<\/li>\n\n\n\n<li>Un <strong>classement par date<\/strong>, de la plus r\u00e9cente \u00e0 la plus ancienne.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-1024x509.png\" alt=\"\" class=\"wp-image-19773\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-2-creer-une-nouvelle-vue\">\u00c9tape 2 : <strong>Cr\u00e9er une nouvelle vue<\/strong><\/h2>\n\n\n\n<p>1\ufe0f\u20e3 <strong>Cliquez sur le bouton bleu \u00ab Cr\u00e9er une vue \u00bb<\/strong>.<br>\ud83d\udccc <strong>Pourquoi cr\u00e9er une vue ?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Organisez vos affectations selon vos besoins.<\/li>\n\n\n\n<li>Contrairement aux autres grilles, une vue <strong>enregistre vos tris, filtres et colonnes<\/strong>.<\/li>\n\n\n\n<li>Vous pouvez quitter la page et <strong>retrouver la vue telle que vous l&rsquo;avez laiss\u00e9e<\/strong>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-1024x509.png\" alt=\"\" class=\"wp-image-19774\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Bouton-nouvelle-vue-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>2\ufe0f\u20e3 <strong>Nommez votre vue<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cliquez sur <strong>\u00ab Cr\u00e9er la vue \u00bb<\/strong> pour l\u2019enregistrer.<\/li>\n\n\n\n<li>Saisissez un <strong>nom<\/strong> pour votre nouvelle vue.<\/li>\n\n\n\n<li>Vous pouvez traduire la vue via l\u2019<strong>outil de traduction<\/strong>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-1024x509.png\" alt=\"\" class=\"wp-image-19782\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Nom-de-la-nouvelle-vue-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-3-personnaliser-la-vue\">\u00c9tape 3 : <strong>Personnaliser la vue<\/strong><\/h2>\n\n\n\n<p>\ud83c\udfaf <strong>Filtrer les affectations<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cliquez sur <strong>\u00ab Filtrer \u00bb<\/strong>.<\/li>\n\n\n\n<li>S\u00e9lectionnez la valeur d\u00e9sir\u00e9e (un outil de recherche est disponible).<\/li>\n\n\n\n<li>Triez les affectations par <strong>ordre croissant ou d\u00e9croissant<\/strong>.<\/li>\n\n\n\n<li>Cliquez sur <strong>\u00ab FILTRER \u00bb<\/strong> pour appliquer les changements.<\/li>\n<\/ol>\n\n\n\n<p>\ud83d\udcca <strong>Afficher ou masquer des colonnes<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cliquez sur <strong>l\u2019ic\u00f4ne avec trois petits points<\/strong>.<\/li>\n\n\n\n<li>S\u00e9lectionnez <strong>\u00ab Colonnes \u00bb<\/strong> pour g\u00e9rer l&rsquo;affichage.<\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udd39 <strong>Mise en \u00e9vidence des nouveaux messages<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une <strong>ligne verticale bleue<\/strong> appara\u00eet au d\u00e9but de la ligne de l\u2019affectation.<\/li>\n\n\n\n<li>Les <strong>textes en gras<\/strong> signalent les nouveaux messages dans la grille.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-1024x509.png\" alt=\"\" class=\"wp-image-19781\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Recheche-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-4-modifier-ou-supprimer-une-vue\">\u00c9tape 4 : <strong>Modifier ou supprimer une vue<\/strong><\/h2>\n\n\n\n<p>\ud83d\udee0 <strong>Modifier une vue<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Votre vue appara\u00eet dans la barre des t\u00e2ches du menu d&rsquo;affectation.<\/li>\n\n\n\n<li>Cliquez sur <strong>l\u2019ic\u00f4ne d\u2019engrenage<\/strong>, puis sur <strong>\u00ab \u00c9diter la vue \u00bb<\/strong>.<\/li>\n\n\n\n<li>Vous pouvez <strong>renommer<\/strong> et <strong>traduire<\/strong> la vue.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-1024x509.png\" alt=\"\" class=\"wp-image-19775\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Editer-ou-supprimer-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\ud83d\uddd1 <strong>Supprimer une vue<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cliquez sur <strong>l\u2019ic\u00f4ne d\u2019engrenage<\/strong>, puis sur <strong>\u00ab Supprimer la vue \u00bb<\/strong>.<\/li>\n\n\n\n<li>Une confirmation s\u2019affiche : cliquez sur <strong>\u00ab Supprimer \u00bb<\/strong> pour valider.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-1024x509.png\" alt=\"\" class=\"wp-image-19776\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Supprimer-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etape-5-modifier-ou-supprimer-une-vue\">\u00c9tape 5 : <strong>Modifier ou supprimer une vue<\/strong><\/h2>\n\n\n\n<p>Si l\u2019option multilingue est activ\u00e9e dans les param\u00e8tres du Tableau de bord :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un bouton <strong>\u00ab Traduire \u00bb<\/strong> appara\u00eet dans l\u2019en-t\u00eate.<\/li>\n\n\n\n<li>Le contenu en <strong>Fran\u00e7ais<\/strong> est affich\u00e9 en <strong>lecture seule<\/strong> avec une <strong>bande bleue<\/strong> \u00e0 gauche.<\/li>\n\n\n\n<li>Des champs de saisie permettent d\u2019<strong>ajouter la traduction<\/strong>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-1024x509.png\" alt=\"\" class=\"wp-image-19780\" srcset=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-1024x509.png 1024w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-300x149.png 300w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-768x382.png 768w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-1536x764.png 1536w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-2048x1018.png 2048w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-18x9.png 18w, https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Traduire-1-360x179.png 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Cet article d\u00e9crit comment cr\u00e9er une vue personnalis\u00e9e pour g\u00e9rer vos requ\u00eates. Si vous n\u2019avez pas votre compte V+, cliquez ici pour une d\u00e9monstration. \u00c9tape 1 : Acc\u00e9der au module Requ\u00eate Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur \u00ab Requ\u00eate \u00bb. \ud83d\udccc Par d\u00e9faut, vous acc\u00e9dez \u00e0 l&rsquo;onglet \u00ab Mes affectations \u00bb, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","footnotes":""},"doc_category":[60],"doc_tag":[],"knowledge_base":[55],"class_list":["post-3793","docs","type-docs","status-publish","hentry","doc_category-approfondir-requete","knowledge_base-requetes-citoyennes"],"acf":[],"year_month":"2026-05","word_count":375,"total_views":"1206","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"David Teixeira","author_nicename":"davidteix","author_url":"https:\/\/modellium.com\/en\/author\/davidteix\/"},"doc_category_info":[{"term_name":"Approfondir","term_url":"https:\/\/modellium.com\/en\/banque-de-connaissances\/requetes-citoyennes\/approfondir-requete\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cr\u00e9er une une vue personnalis\u00e9e - Modellium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/modellium.com\/en\/docs\/creer-une-une-vue-personnalisee\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9er une une vue personnalis\u00e9e - Modellium\" \/>\n<meta property=\"og:description\" content=\"Cet article d\u00e9crit comment cr\u00e9er une vue personnalis\u00e9e pour g\u00e9rer vos requ\u00eates. Si vous n\u2019avez pas votre compte V+, cliquez ici pour une d\u00e9monstration. \u00c9tape 1 : Acc\u00e9der au module Requ\u00eate Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur \u00ab Requ\u00eate \u00bb. \ud83d\udccc Par d\u00e9faut, vous acc\u00e9dez \u00e0 l&rsquo;onglet \u00ab Mes affectations \u00bb, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/modellium.com\/en\/docs\/creer-une-une-vue-personnalisee\/\" \/>\n<meta property=\"og:site_name\" content=\"Modellium\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Modellium\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T20:38:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3833\" \/>\n\t<meta property=\"og:image:height\" content=\"1906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/\",\"url\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/\",\"name\":\"Cr\u00e9er une une vue personnalis\u00e9e - Modellium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Affectations-1024x509.png\",\"datePublished\":\"2025-02-06T20:03:59+00:00\",\"dateModified\":\"2025-02-06T20:38:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Affectations-1024x509.png\",\"contentUrl\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Affectations-1024x509.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/modellium.com\\\/docs\\\/creer-une-une-vue-personnalisee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explorez les produits\",\"item\":\"https:\\\/\\\/modellium.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Requ\u00eates citoyennes\",\"item\":\"https:\\\/\\\/modellium.com\\\/banque-de-connaissances\\\/requetes-citoyennes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cr\u00e9er une une vue personnalis\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/modellium.com\\\/#website\",\"url\":\"https:\\\/\\\/modellium.com\\\/\",\"name\":\"Modellium\",\"description\":\"Solutions num\u00e9riques innovantes pour le domaine municipal\",\"publisher\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/modellium.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/modellium.com\\\/#organization\",\"name\":\"Modellium\",\"url\":\"https:\\\/\\\/modellium.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/modellium.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-modellium-desktop.svg\",\"contentUrl\":\"https:\\\/\\\/modellium.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-modellium-desktop.svg\",\"width\":149,\"height\":30,\"caption\":\"Modellium\"},\"image\":{\"@id\":\"https:\\\/\\\/modellium.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Modellium\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/modellium\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cr\u00e9er une une vue personnalis\u00e9e - Modellium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/modellium.com\/en\/docs\/creer-une-une-vue-personnalisee\/","og_locale":"en_US","og_type":"article","og_title":"Cr\u00e9er une une vue personnalis\u00e9e - Modellium","og_description":"Cet article d\u00e9crit comment cr\u00e9er une vue personnalis\u00e9e pour g\u00e9rer vos requ\u00eates. Si vous n\u2019avez pas votre compte V+, cliquez ici pour une d\u00e9monstration. \u00c9tape 1 : Acc\u00e9der au module Requ\u00eate Dans le menu principal \u00e0 gauche de l\u2019\u00e9cran, cliquez sur \u00ab Requ\u00eate \u00bb. \ud83d\udccc Par d\u00e9faut, vous acc\u00e9dez \u00e0 l&rsquo;onglet \u00ab Mes affectations \u00bb, [&hellip;]","og_url":"https:\/\/modellium.com\/en\/docs\/creer-une-une-vue-personnalisee\/","og_site_name":"Modellium","article_publisher":"https:\/\/www.facebook.com\/Modellium\/","article_modified_time":"2025-02-06T20:38:10+00:00","og_image":[{"width":3833,"height":1906,"url":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/","url":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/","name":"Cr\u00e9er une une vue personnalis\u00e9e - Modellium","isPartOf":{"@id":"https:\/\/modellium.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/#primaryimage"},"image":{"@id":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/#primaryimage"},"thumbnailUrl":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-1024x509.png","datePublished":"2025-02-06T20:03:59+00:00","dateModified":"2025-02-06T20:38:10+00:00","breadcrumb":{"@id":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/#primaryimage","url":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-1024x509.png","contentUrl":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/09\/Affectations-1024x509.png"},{"@type":"BreadcrumbList","@id":"https:\/\/modellium.com\/docs\/creer-une-une-vue-personnalisee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explorez les produits","item":"https:\/\/modellium.com\/"},{"@type":"ListItem","position":2,"name":"Requ\u00eates citoyennes","item":"https:\/\/modellium.com\/banque-de-connaissances\/requetes-citoyennes\/"},{"@type":"ListItem","position":3,"name":"Cr\u00e9er une une vue personnalis\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/modellium.com\/#website","url":"https:\/\/modellium.com\/","name":"Modellium","description":"Solutions num\u00e9riques innovantes pour le domaine municipal","publisher":{"@id":"https:\/\/modellium.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/modellium.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/modellium.com\/#organization","name":"Modellium","url":"https:\/\/modellium.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/modellium.com\/#\/schema\/logo\/image\/","url":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/06\/logo-modellium-desktop.svg","contentUrl":"https:\/\/modellium.com\/wp-content\/uploads\/2023\/06\/logo-modellium-desktop.svg","width":149,"height":30,"caption":"Modellium"},"image":{"@id":"https:\/\/modellium.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Modellium\/","https:\/\/www.linkedin.com\/company\/modellium\/"]}]}},"jetpack_sharing_enabled":true,"knowledge_base_info":[{"term_name":"Requ\u00eates citoyennes","term_url":"https:\/\/modellium.com\/en\/banque-de-connaissances\/requetes-citoyennes\/","term_slug":"requetes-citoyennes"}],"knowledge_base_slug":["requetes-citoyennes"],"_links":{"self":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs\/3793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/comments?post=3793"}],"version-history":[{"count":63,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs\/3793\/revisions"}],"predecessor-version":[{"id":20703,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/docs\/3793\/revisions\/20703"}],"wp:attachment":[{"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/media?parent=3793"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/doc_category?post=3793"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/doc_tag?post=3793"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/modellium.com\/en\/wp-json\/wp\/v2\/knowledge_base?post=3793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}